{"id":78818,"date":"2025-05-27T17:05:52","date_gmt":"2025-05-27T15:05:52","guid":{"rendered":"https:\/\/maisonroca.ad\/?page_id=78818"},"modified":"2026-01-14T09:40:27","modified_gmt":"2026-01-14T08:40:27","slug":"chaumet","status":"publish","type":"page","link":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/","title":{"rendered":"Chaumet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"78818\" class=\"elementor elementor-78818 elementor-75283\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19b93de7 e-flex e-con-boxed e-con e-parent\" data-id=\"19b93de7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7dafa032 e-con-full e-flex e-con e-child\" data-id=\"7dafa032\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b58ae09 elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"5b58ae09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" aria-label=\"Breadcrumb\">Inicio<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a07c242 e-flex e-con-boxed e-con e-child\" data-id=\"6a07c242\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-381a1a47 e-con-full e-flex e-con e-child\" data-id=\"381a1a47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e02ee43 elementor-widget elementor-widget-heading\" data-id=\"2e02ee43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CHAUMET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5a1efb elementor-widget elementor-widget-text-editor\" data-id=\"5e5a1efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Amb m\u00e9s de dos segles d\u2019hist\u00f2ria al cor de la pla\u00e7a Vend\u00f4me, <b>Chaumet<\/b>\u00a0simbolitza l\u2019eleg\u00e0ncia imperial i l\u2019art de la joieria francesa. Inspirades per la natura, l\u2019amor i la noblesa, les seves creacions s\u00f3n aut\u00e8ntics poemes en or i pedres precioses. Cada joia transmet emoci\u00f3, distinci\u00f3 i un savoir-faire inconfusible.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29d2420b e-con-full e-flex e-con e-child\" data-id=\"29d2420b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13ae4438 elementor-widget elementor-widget-image\" data-id=\"13ae4438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/08\/Chaumet-pag-marca-MR.jpg\" class=\"attachment-large size-large wp-image-78625\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/08\/Chaumet-pag-marca-MR.jpg 800w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/08\/Chaumet-pag-marca-MR-300x169.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/08\/Chaumet-pag-marca-MR-768x432.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/08\/Chaumet-pag-marca-MR-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49fa7e81 e-con-full e-flex e-con e-child\" data-id=\"49fa7e81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"woocommerce elementor-element elementor-element-5b31036f elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"5b31036f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_skin&quot;:&quot;product&quot;,&quot;template_id&quot;:55678,&quot;columns&quot;:4,&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;pagination_load_type&quot;:&quot;page_reload&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.product\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\r\n\t\t<style id=\"loop-55678\">.elementor-55678 .elementor-element.elementor-element-1a90aa27{--display:flex;--justify-content:space-between;--background-transition:0.3s;--border-radius:10px 10px 10px 10px;}.elementor-55678 .elementor-element.elementor-element-1a90aa27:not(.elementor-motion-effects-element-type-background), .elementor-55678 .elementor-element.elementor-element-1a90aa27 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-55678 .elementor-element.elementor-element-1a90aa27:hover{background-color:#B3291E;}.elementor-55678 .elementor-element.elementor-element-3c7cec68{--display:flex;}.elementor-55678 .elementor-element.elementor-element-4331493a img{max-width:255px;height:320px;object-fit:cover;object-position:center center;}.elementor-55678 .elementor-element.elementor-element-6d3b051e{text-align:center;}.elementor-55678 .elementor-element.elementor-element-6d3b051e .elementor-heading-title{font-size:14px;text-transform:uppercase;color:#0C5DB3;}.elementor-55678 .elementor-element.elementor-element-3eb873a4{text-align:center;}.woocommerce .elementor-55678 .elementor-element.elementor-element-3eb873a4 .price{color:#0C5DB3;}.elementor-55678 .elementor-element.elementor-element-1369aa13 .elementor-button{fill:#FFFFFF;color:#FFFFFF;}.elementor-55678 .elementor-element.elementor-element-1369aa13 > .elementor-widget-container{margin:0px 0px 5px 0px;}.elementor-55678 .elementor-element.elementor-element-1369aa13.elementor-element{--order:99999 \/* order end hack *\/;}\/* Start custom CSS for woocommerce-product-title, class: .elementor-element-6d3b051e *\/.au-product-grid:hover #au-product-title h4 {\n    color: white;\n}\/* End custom CSS *\/\n\/* Start custom CSS for woocommerce-product-price, class: .elementor-element-3eb873a4 *\/.au-product-grid:hover #au-product-price p {\n    color: white;\n}\/* End custom CSS *\/\n\/* Start custom CSS for button, class: .elementor-element-1369aa13 *\/.au-product-grid:hover #au-descubre-boton {\n    background-color: white;\n    color: var(--e-global-color-079060f);\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-45190 post-45190 product type-product status-publish has-post-thumbnail product_cat-dodo-es product_cat-joyas product_tag-colgantes product_tag-dinho-van product_tag-dodo-2 product_tag-oro-rosa first instock sold-individually purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-65620\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1-100x100.jpg 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc2009-zodar-0009a-1.jpg 1164w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/colgante-dodo-symbols-aries-de-plata-y-oro-rosa\/\">COLGANTE DODO SYMBOLS ARIES DE PLATA Y ORO ROSA<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>171,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/colgante-dodo-symbols-aries-de-plata-y-oro-rosa\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-45183 post-45183 product type-product status-publish has-post-thumbnail product_cat-dodo-es product_cat-joyas product_tag-dodo-2 product_tag-oro-rosa product_tag-pendientes  instock sold-individually purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-64935\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1-100x100.jpg 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dhc2003-knot0-0009r-1.jpg 1164w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/mono-pendiente-dodo-nodo-pm-de-oro-rosa\/\">MONO PENDIENTE DODO NODO PM DE ORO ROSA<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>261,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/mono-pendiente-dodo-nodo-pm-de-oro-rosa\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-44757 post-44757 product type-product status-publish has-post-thumbnail product_cat-oris-es product_cat-relojes product_tag-acero product_tag-automatic-2-2 product_tag-de-100-a-300-metres-es product_tag-oris-2 product_tag-rellotges-es product_tag-senor product_tag-verde  instock sold-individually purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-1024x1024.jpg\" class=\"attachment-large size-large wp-image-55498\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-700x700.jpg 700w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB-100x100.jpg 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/01-400-7763-4157-07-8-24-09PEB.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/reloj-oris-aquis-date-calibre-400-de-4350-mm-de-acero\/\">RELOJ ORIS AQUIS DATE CALIBRE 400 DE 43,50 MM DE ACERO<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>3.220,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/reloj-oris-aquis-date-calibre-400-de-4350-mm-de-acero\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-44338 post-44338 product type-product status-publish has-post-thumbnail product_cat-gigi-clozeau-es product_cat-joyas product_tag-gigi-clozeau-3-2 product_tag-oro-rosa product_tag-pulseras product_tag-resina-2 product_tag-turquesa-2 product_tag-verde last instock sold-individually purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-1024x1024.jpg\" class=\"attachment-large size-large wp-image-6412\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-700x700.jpg 700w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33-100x100.jpg 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/b3co001r33.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/pulsera-gigi-clozeau-madone-cruz-de-oro-y-resina\/\">PULSERA GIGI CLOZEAU CRUZ DE ORO Y RESINA VERDE TURQUESA<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>323,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/pulsera-gigi-clozeau-madone-cruz-de-oro-y-resina\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-44594 post-44594 product type-product status-publish has-post-thumbnail product_cat-joyas product_cat-messika-es product_tag-diamantes product_tag-messika-2-2 product_tag-oro-rosa product_tag-pulseras first instock sold-individually purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-1024x1024.png\" class=\"attachment-large size-large wp-image-61748\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-1024x1024.png 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-300x300.png 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-150x150.png 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-768x768.png 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-400x400.png 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-600x600.png 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom-100x100.png 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/14098-pg-Photoroom.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/pulsera-messika-cares-de-oro-rosa-diamantes-y-cordon-crema\/\">PULSERA MESSIKA CARE(S) DE ORO ROSA, DIAMANTES Y CORD\u00d3N CREMA<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>1.318,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/pulsera-messika-cares-de-oro-rosa-diamantes-y-cordon-crema\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-72898 post-72898 product type-product status-publish has-post-thumbnail product_cat-joyas product_cat-maison-roca-es product_tag-anillos product_tag-diamantes product_tag-maison-roca-es product_tag-naturals-es product_tag-oro-blanco product_tag-topacios  instock shipping-taxable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-1024x1024.jpg\" class=\"attachment-large size-large wp-image-72644\" alt=\"Anell d\u2019or blanc amb diamants naturals i safir de Maison Roca\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L-100x100.jpg 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2025\/05\/RD865FMPWA00L.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/anillo-oro-blanco-diamantes-zafiro\/\">ANILLO MAISON ROCA DE ORO BLANCO, DIAMANTES NATURALES Y ZAFIRO<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/anillo-oro-blanco-diamantes-zafiro\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-45282 post-45282 product type-product status-publish has-post-thumbnail product_cat-joyas product_cat-maison-roca-es product_tag-anillos product_tag-diamantes product_tag-maison-roca-tracemark-2 product_tag-oro-blanco  instock sold-individually product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-1024x1024.jpg\" class=\"attachment-large size-large wp-image-9124\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-1536x1536.jpg 1536w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa.jpg 2048w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-700x700.jpg 700w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/r1104124nwa-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/anillo-solitario-maison-roca-tracemark-oro-blanco-y-diamante-4\/\">ANILLO SOLITARIO MAISON ROCA &#038; Tracemark ORO BLANCO Y DIAMANTE<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/anillo-solitario-maison-roca-tracemark-oro-blanco-y-diamante-4\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55678\" class=\"elementor elementor-55678 elementor-773 elementor-773 e-loop-item e-loop-item-45202 post-45202 product type-product status-publish has-post-thumbnail product_cat-dodo-es product_cat-joyas product_tag-colgantes product_tag-dodo-2 product_tag-oro-rosa last instock sold-individually purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\r\n\t\t\t<div class=\"elementor-element elementor-element-1a90aa27 au-product-grid e-flex e-con-boxed e-con e-parent\" data-id=\"1a90aa27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c7cec68 equal-list e-flex e-con-boxed e-con e-child\" data-id=\"3c7cec68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4331493a elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4331493a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-65167\" alt=\"\" srcset=\"https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-1024x1024.jpg 1024w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-300x300.jpg 300w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-150x150.jpg 150w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-768x768.jpg 768w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-400x400.jpg 400w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-600x600.jpg 600w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1-100x100.jpg 100w, https:\/\/maisonroca.ad\/wp-content\/uploads\/2024\/07\/dmc4011-heart-ero9r-1.jpg 1164w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b051e elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"6d3b051e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-title\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"product_title entry-title elementor-heading-title elementor-size-default\"><a href=\"https:\/\/maisonroca.ad\/es\/tienda\/colgante-dodo-cuore-de-oro-rosa-con-esmalte-rojo-efecto-nacar\/\">COLGANTE DODO CUORE DE ORO ROSA CON ESMALTE ROJO EFECTO N\u00c1CAR<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb873a4 elementor-widget elementor-widget-woocommerce-product-price\" data-id=\"3eb873a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"au-product-price\" data-widget_type=\"woocommerce-product-price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>153,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1369aa13 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1369aa13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maisonroca.ad\/es\/tienda\/colgante-dodo-cuore-de-oro-rosa-con-esmalte-rojo-efecto-nacar\/\" id=\"au-descubre-boton\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\r\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"180\" data-next-page=\"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/page\/2\/\"><\/div>\r\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Paginaci\u00f3n\">\r\n\t\t\t<span class=\"page-numbers prev\">Previous<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">P\u00e1gina<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/page\/2\/\"><span class=\"elementor-screen-only\">P\u00e1gina<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/page\/3\/\"><span class=\"elementor-screen-only\">P\u00e1gina<\/span>3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/page\/180\/\"><span class=\"elementor-screen-only\">P\u00e1gina<\/span>180<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/page\/2\/\">Next<\/a>\t\t<\/nav>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":16471,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-78818","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chaumet - Maison Roca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaumet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/\" \/>\n<meta property=\"og:site_name\" content=\"Maison Roca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maisonroca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T08:40:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/joyeria\\\/chaumet\\\/\",\"url\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/joyeria\\\/chaumet\\\/\",\"name\":\"Chaumet - Maison Roca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/#website\"},\"datePublished\":\"2025-05-27T15:05:52+00:00\",\"dateModified\":\"2026-01-14T08:40:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/joyeria\\\/chaumet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maisonroca.ad\\\/es\\\/joyeria\\\/chaumet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/joyeria\\\/chaumet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joyer\u00eda\",\"item\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/joyeria\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chaumet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/\",\"name\":\"Maison Roca\",\"description\":\"Bold Luxury Life - joieria d&#039;autor - Andorra\",\"publisher\":{\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/#organization\",\"name\":\"Maison Roca\",\"url\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maisonroca.ad\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/icono.png\",\"contentUrl\":\"https:\\\/\\\/maisonroca.ad\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/icono.png\",\"width\":512,\"height\":512,\"caption\":\"Maison Roca\"},\"image\":{\"@id\":\"https:\\\/\\\/maisonroca.ad\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/maisonroca\",\"https:\\\/\\\/www.instagram.com\\\/maisonroca\\\/\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"153.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"DMC4011-HEART-ERO9R\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chaumet - Maison Roca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/","og_locale":"es_ES","og_type":"article","og_title":"Chaumet","og_url":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/","og_site_name":"Maison Roca","article_publisher":"https:\/\/www.facebook.com\/maisonroca","article_modified_time":"2026-01-14T08:40:27+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/","url":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/","name":"Chaumet - Maison Roca","isPartOf":{"@id":"https:\/\/maisonroca.ad\/es\/#website"},"datePublished":"2025-05-27T15:05:52+00:00","dateModified":"2026-01-14T08:40:27+00:00","breadcrumb":{"@id":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maisonroca.ad\/es\/joyeria\/chaumet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maisonroca.ad\/es\/"},{"@type":"ListItem","position":2,"name":"Joyer\u00eda","item":"https:\/\/maisonroca.ad\/es\/joyeria\/"},{"@type":"ListItem","position":3,"name":"Chaumet"}]},{"@type":"WebSite","@id":"https:\/\/maisonroca.ad\/es\/#website","url":"https:\/\/maisonroca.ad\/es\/","name":"Maison Roca","description":"Bold Luxury Life - joieria d&#039;autor - Andorra","publisher":{"@id":"https:\/\/maisonroca.ad\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maisonroca.ad\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maisonroca.ad\/es\/#organization","name":"Maison Roca","url":"https:\/\/maisonroca.ad\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maisonroca.ad\/es\/#\/schema\/logo\/image\/","url":"https:\/\/maisonroca.ad\/wp-content\/uploads\/2023\/10\/icono.png","contentUrl":"https:\/\/maisonroca.ad\/wp-content\/uploads\/2023\/10\/icono.png","width":512,"height":512,"caption":"Maison Roca"},"image":{"@id":"https:\/\/maisonroca.ad\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/maisonroca","https:\/\/www.instagram.com\/maisonroca\/"]}]},"product_price_amount":"153.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"DMC4011-HEART-ERO9R","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/comments?post=78818"}],"version-history":[{"count":1,"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/revisions"}],"predecessor-version":[{"id":78827,"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/78818\/revisions\/78827"}],"up":[{"embeddable":true,"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/pages\/16471"}],"wp:attachment":[{"href":"https:\/\/maisonroca.ad\/es\/wp-json\/wp\/v2\/media?parent=78818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}